{"id":27369,"date":"2023-08-07T15:19:25","date_gmt":"2023-08-07T18:19:25","guid":{"rendered":"https:\/\/www.galgo.com\/?page_id=27369"},"modified":"2023-09-04T16:55:00","modified_gmt":"2023-09-04T19:55:00","slug":"socopur","status":"publish","type":"page","link":"https:\/\/www.galgo.com\/pe\/socopur","title":{"rendered":"Socopur"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"27369\" class=\"elementor elementor-27369\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17a4657 elementor-section-height-min-height elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"17a4657\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-af8d0f2\" data-id=\"af8d0f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0716630 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0716630\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cdc49b1\" data-id=\"cdc49b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c37aa1b elementor-widget elementor-widget-image\" data-id=\"5c37aa1b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.4 - 12-03-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"208\" height=\"55\" src=\"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/06\/galgologofooter-1.png\" class=\"attachment-large size-large wp-image-20214\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d9bd5aa\" data-id=\"d9bd5aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-447b5aa elementor-widget elementor-widget-image\" data-id=\"447b5aa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"817\" height=\"129\" src=\"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/08\/logo-socopur-color-.png\" class=\"attachment-large size-large wp-image-27388\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/08\/logo-socopur-color-.png 817w, https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/08\/logo-socopur-color--300x47.png 300w, https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/08\/logo-socopur-color--768x121.png 768w\" sizes=\"(max-width: 817px) 100vw, 817px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a8d01b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8d01b8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-fef7530\" data-id=\"fef7530\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f53efd elementor-widget elementor-widget-heading\" data-id=\"8f53efd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.4 - 12-03-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">\u00bfNecesitas financiar tu moto?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-446cf8f\" data-id=\"446cf8f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93b7d79 elementor-widget elementor-widget-image\" data-id=\"93b7d79\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"635\" height=\"300\" src=\"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/08\/socopur-mobile.jpg\" class=\"attachment-large size-large wp-image-27407\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/08\/socopur-mobile.jpg 635w, https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/08\/socopur-mobile-300x142.jpg 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f132bf elementor-section-height-min-height elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3f132bf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-806cc48\" data-id=\"806cc48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a79ca36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a79ca36\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-58a55b0\" data-id=\"58a55b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-617504a elementor-widget elementor-widget-image\" data-id=\"617504a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"208\" height=\"55\" src=\"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/06\/galgologofooter-1.png\" class=\"attachment-large size-large wp-image-20214\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b8983b0\" data-id=\"b8983b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7317b41 elementor-widget elementor-widget-image\" data-id=\"7317b41\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"817\" height=\"129\" src=\"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/08\/logo-socopur-color-.png\" class=\"attachment-large size-large wp-image-27388\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/08\/logo-socopur-color-.png 817w, https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/08\/logo-socopur-color--300x47.png 300w, https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/08\/logo-socopur-color--768x121.png 768w\" sizes=\"(max-width: 817px) 100vw, 817px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d7c71ef elementor-widget elementor-widget-heading\" data-id=\"1d7c71ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfNecesitas financiar tu moto?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8168441\" data-id=\"8168441\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70b1d1dc elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"70b1d1dc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c405012\" data-id=\"c405012\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d6d3eba elementor-widget elementor-widget-text-editor\" data-id=\"3d6d3eba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.4 - 12-03-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<strong>Postula en el formulario<\/strong>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17b06076 elementor-widget elementor-widget-text-editor\" data-id=\"17b06076\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">y avanza con nuestros <\/span><b>aliados de Galgo.<\/b><span style=\"font-weight: 400;\"> Est\u00e1s a un par de clics de la <\/span><b>moto de tus sue\u00f1os<\/b><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-516b8b41\" data-id=\"516b8b41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-35214874 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35214874\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3674f265\" data-id=\"3674f265\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1da45831 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"1da45831\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.11.5 - 12-03-2023 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#c2cbd2}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"Form Moto\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"27369\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"1da45831\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Galgo\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_26286df elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"Autenticaci\u00f3n\" data-previousButton=\"&lt; Anterior\" data-nextButton=\"Siguiente &gt;\" data-iconUrl=\"\" data-iconLibrary=\"fas fa-star\" data-icon=\"&lt;svg class=&quot;e-font-icon-svg e-fas-star&quot; viewBox=&quot;0 0 576 512&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;&gt;&lt;path d=&quot;M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z&quot;&gt;&lt;\/path&gt;&lt;\/svg&gt;\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-documento elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-documento\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tDocumento de Identidad\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[documento]\" id=\"form-field-documento\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"DNI\">DNI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Carn\u00e9t de extranjer\u00eda\">Carn\u00e9t de extranjer\u00eda<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CPP\">CPP<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pasaporte\">Pasaporte<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-numerodocumento elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-numerodocumento\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tN\u00b0 de documento de identidad\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[numerodocumento]\" id=\"form-field-numerodocumento\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" aria-required=\"true\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-whatsapp elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-whatsapp\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tN\u00b0 de Whatsapp (sin +51)\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[whatsapp]\" id=\"form-field-whatsapp\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" aria-required=\"true\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCorreo Electr\u00f3nico\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-date elementor-field-group elementor-column elementor-field-group-field_c54fe9e elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_c54fe9e\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tFecha de Nacimiento\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\n\t\t<input type=\"date\" name=\"form_fields[field_c54fe9e]\" id=\"form-field-field_c54fe9e\" class=\"elementor-field elementor-size-sm  elementor-field-textual elementor-date-field elementor-use-native\" required=\"required\" aria-required=\"true\" pattern=\"[0-9]{4}-[0-9]{2}-[0-9]{2}\" min=\"1945-01-01\" max=\"2004-01-01\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_871c989 elementor-col-50 elementor-sm-50\">\n\t\t\t\t\t<\/br><\/br>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_a52fbb1 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"Datos Personales\" data-previousButton=\"&lt; Anterior\" data-nextButton=\"&gt;\" data-iconUrl=\"\" data-iconLibrary=\"fas fa-star\" data-icon=\"&lt;svg class=&quot;e-font-icon-svg e-fas-star&quot; viewBox=&quot;0 0 576 512&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;&gt;&lt;path d=&quot;M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z&quot;&gt;&lt;\/path&gt;&lt;\/svg&gt;\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-nombres elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-nombres\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNombre completo\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[nombres]\" id=\"form-field-nombres\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_5482a0a elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_5482a0a\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tG\u00e9nero\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_5482a0a]\" id=\"form-field-field_5482a0a\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Femenino\">Femenino<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Masculino\">Masculino<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Prefiero no especificar\">Prefiero no especificar<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-nacionalidad elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-nacionalidad\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNacionalidad\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[nacionalidad]\" id=\"form-field-nacionalidad\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Venezuela\">Venezuela<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Colombia\">Colombia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Per\u00fa\">Per\u00fa<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Espa\u00f1a\">Espa\u00f1a<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Estados Unidos\">Estados Unidos<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ecuador\">Ecuador<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Argentina\">Argentina<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Chile\">Chile<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Brasil\">Brasil<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"China\">China<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Bolivia\">Bolivia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"M\u00e9xico\">M\u00e9xico<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Otro\">Otro<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-ciudad elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-ciudad\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tDepartamento de residencia actual\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[ciudad]\" id=\"form-field-ciudad\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Amazonas\">Amazonas<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"\u00c1ncash\">\u00c1ncash<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Apur\u00edmac\">Apur\u00edmac<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Arequipa\">Arequipa<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ayacucho\">Ayacucho<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Cajamarca\">Cajamarca<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Prov. Const. del Callao\">Prov. Const. del Callao<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Cusco\">Cusco<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Huancavelica\">Huancavelica<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Hu\u00e1nuco\">Hu\u00e1nuco<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ica\">Ica<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Jun\u00edn\">Jun\u00edn<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"La Libertad\">La Libertad<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lambayeque\">Lambayeque<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lima\">Lima<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Loreto\">Loreto<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Madre de Dios\">Madre de Dios<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Moquegua\">Moquegua<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pasco\">Pasco<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Piura\">Piura<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Puno\">Puno<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"San Mart\u00edn\">San Mart\u00edn<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Tacna\">Tacna<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Tumbes\">Tumbes<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ucayali\">Ucayali<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-situacionlaboral elementor-col-50 elementor-sm-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-situacionlaboral\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tSituaci\u00f3n laboral\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[situacionlaboral]\" id=\"form-field-situacionlaboral\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" Emprendedor informal\">Emprendedor <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Trabajador dependiente con contrato indefinido\">Trabajador dependiente con contrato indefinido<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Trabajador dependiente con contrato a plazo fijo\">Trabajador dependiente con contrato a plazo fijo<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Trabajador dependiente con solo constancia de trabajo\">Trabajador dependiente con solo constancia de trabajo<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Independiente con recibos de honorarios\">Independiente con recibos de honorarios<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Repartidor o conductor de apps (Uber, PedidosYa, etc)\">Repartidor o conductor de apps (Uber, PedidosYa, etc)<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Trabajador informal\">Trabajador informal<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Persona natural con negocio\">Persona natural con negocio<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Persona jur\u00eddica\">Persona jur\u00eddica<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Estoy en b\u00fasqueda de trabajo\">Estoy en b\u00fasqueda de trabajo<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_edb40b2 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_edb40b2\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u00bfCu\u00e1ndo quieres conseguir tu cr\u00e9dito?\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_edb40b2]\" id=\"form-field-field_edb40b2\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"En m\u00e1ximo 1 semana\">En m\u00e1ximo 1 semana<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Entre 1 semana y 1 mes\">Entre 1 semana y 1 mes<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Entre 1 y 3 meses\">Entre 1 y 3 meses<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"En m\u00e1s de 3 meses\">En m\u00e1s de 3 meses<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-number elementor-field-group elementor-column elementor-field-group-field_1a83797 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_1a83797\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tIngreso Mensual\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t<input type=\"number\" name=\"form_fields[field_1a83797]\" id=\"form-field-field_1a83797\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" aria-required=\"true\" min=\"200\" max=\"100000\" >\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-cuandoquiereselcredito elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-cuandoquiereselcredito\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u00bfQu\u00e9 marca te interesa financiar con Galgo?\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[cuandoquiereselcredito]\" id=\"form-field-cuandoquiereselcredito\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Hero\">Hero<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"HUSQVARNA\">HUSQVARNA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lifan\">Lifan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"KTM \">KTM <\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_5e4465c elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_5e4465c]\" id=\"form-field-field_5e4465c\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\" aria-required=\"true\" checked=\"checked\">\n\t\t\t\t<label for=\"form-field-field_5e4465c\">Al llenar este formulario acepto los <strong><a style= color:#000000; href=\"https:\/\/migrante.com.pe\/terminos-y-condiciones-de-migrante\/\/\">T\u00e9rminos y Condiciones de Migrante<\/a><\/strong><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_c023756 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_c023756]\" id=\"form-field-field_c023756\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\" aria-required=\"true\" checked=\"checked\">\n\t\t\t\t<label for=\"form-field-field_c023756\">Estoy de acuerdo con la   <a style=\"color: #000000; font-size: 13px; padding: 2px; font-weight: bold;  \" href=\"https:\/\/migrante.com.pe\/politica-de-privacidad\/\/\">  Pol\u00edtica de privacidad  <\/a><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_8368c58 elementor-col-50 elementor-sm-50\">\n\t\t\t\t\t<\/br><\/br>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text\">\n\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_bbdd525]\" id=\"form-field-field_bbdd525\" class=\"elementor-field elementor-size-sm \" style=\"display:none !important;\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_421bc98 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_421bc98]\" id=\"form-field-field_421bc98\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_17d0772 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_17d0772]\" id=\"form-field-field_17d0772\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_9fd9aaf elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_9fd9aaf]\" id=\"form-field-field_9fd9aaf\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_91da117 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_91da117]\" id=\"form-field-field_91da117\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_cd84408 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_cd84408]\" id=\"form-field-field_cd84408\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_cc3983d elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_cc3983d]\" id=\"form-field-field_cc3983d\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_2c5ca00 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_2c5ca00]\" id=\"form-field-field_2c5ca00\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_4bcab15 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_4bcab15]\" id=\"form-field-field_4bcab15\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_99f529f elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_99f529f]\" id=\"form-field-field_99f529f\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_212099e elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_212099e]\" id=\"form-field-field_212099e\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_94e1825 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_94e1825]\" id=\"form-field-field_94e1825\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_7e7ce99 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_7e7ce99]\" id=\"form-field-field_7e7ce99\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\" elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicita tu cr\u00e9dito<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bc6dfb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bc6dfb7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25895efc\" data-id=\"25895efc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fd5fc36 elementor-widget elementor-widget-text-editor\" data-id=\"3fd5fc36\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<span style=\"color: #FF1616;\"><b>\u00bfCu\u00e1les son los requisitos para obtener un cr\u00e9dito de moto?<\/b><\/span>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5757255b elementor-section-height-min-height elementor-section-items-top elementor-section-content-top elementor-section-boxed elementor-section-height-default\" data-id=\"5757255b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-76bae050\" data-id=\"76bae050\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9445a6 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a9445a6\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fingerprint\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256.12 245.96c-13.25 0-24 10.74-24 24 1.14 72.25-8.14 141.9-27.7 211.55-2.73 9.72 2.15 30.49 23.12 30.49 10.48 0 20.11-6.92 23.09-17.52 13.53-47.91 31.04-125.41 29.48-224.52.01-13.25-10.73-24-23.99-24zm-.86-81.73C194 164.16 151.25 211.3 152.1 265.32c.75 47.94-3.75 95.91-13.37 142.55-2.69 12.98 5.67 25.69 18.64 28.36 13.05 2.67 25.67-5.66 28.36-18.64 10.34-50.09 15.17-101.58 14.37-153.02-.41-25.95 19.92-52.49 54.45-52.34 31.31.47 57.15 25.34 57.62 55.47.77 48.05-2.81 96.33-10.61 143.55-2.17 13.06 6.69 25.42 19.76 27.58 19.97 3.33 26.81-15.1 27.58-19.77 8.28-50.03 12.06-101.21 11.27-152.11-.88-55.8-47.94-101.88-104.91-102.72zm-110.69-19.78c-10.3-8.34-25.37-6.8-33.76 3.48-25.62 31.5-39.39 71.28-38.75 112 .59 37.58-2.47 75.27-9.11 112.05-2.34 13.05 6.31 25.53 19.36 27.89 20.11 3.5 27.07-14.81 27.89-19.36 7.19-39.84 10.5-80.66 9.86-121.33-.47-29.88 9.2-57.88 28-80.97 8.35-10.28 6.79-25.39-3.49-33.76zm109.47-62.33c-15.41-.41-30.87 1.44-45.78 4.97-12.89 3.06-20.87 15.98-17.83 28.89 3.06 12.89 16 20.83 28.89 17.83 11.05-2.61 22.47-3.77 34-3.69 75.43 1.13 137.73 61.5 138.88 134.58.59 37.88-1.28 76.11-5.58 113.63-1.5 13.17 7.95 25.08 21.11 26.58 16.72 1.95 25.51-11.88 26.58-21.11a929.06 929.06 0 0 0 5.89-119.85c-1.56-98.75-85.07-180.33-186.16-181.83zm252.07 121.45c-2.86-12.92-15.51-21.2-28.61-18.27-12.94 2.86-21.12 15.66-18.26 28.61 4.71 21.41 4.91 37.41 4.7 61.6-.11 13.27 10.55 24.09 23.8 24.2h.2c13.17 0 23.89-10.61 24-23.8.18-22.18.4-44.11-5.83-72.34zm-40.12-90.72C417.29 43.46 337.6 1.29 252.81.02 183.02-.82 118.47 24.91 70.46 72.94 24.09 119.37-.9 181.04.14 246.65l-.12 21.47c-.39 13.25 10.03 24.31 23.28 24.69.23.02.48.02.72.02 12.92 0 23.59-10.3 23.97-23.3l.16-23.64c-.83-52.5 19.16-101.86 56.28-139 38.76-38.8 91.34-59.67 147.68-58.86 69.45 1.03 134.73 35.56 174.62 92.39 7.61 10.86 22.56 13.45 33.42 5.86 10.84-7.62 13.46-22.59 5.84-33.43z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c07dbaa elementor-widget elementor-widget-text-editor\" data-id=\"c07dbaa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Contar con DNI, CPP o CE<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-17133c84\" data-id=\"17133c84\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-392013f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"392013f\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-money-bill-wave\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M621.16 54.46C582.37 38.19 543.55 32 504.75 32c-123.17-.01-246.33 62.34-369.5 62.34-30.89 0-61.76-3.92-92.65-13.72-3.47-1.1-6.95-1.62-10.35-1.62C15.04 79 0 92.32 0 110.81v317.26c0 12.63 7.23 24.6 18.84 29.46C57.63 473.81 96.45 480 135.25 480c123.17 0 246.34-62.35 369.51-62.35 30.89 0 61.76 3.92 92.65 13.72 3.47 1.1 6.95 1.62 10.35 1.62 17.21 0 32.25-13.32 32.25-31.81V83.93c-.01-12.64-7.24-24.6-18.85-29.47zM48 132.22c20.12 5.04 41.12 7.57 62.72 8.93C104.84 170.54 79 192.69 48 192.69v-60.47zm0 285v-47.78c34.37 0 62.18 27.27 63.71 61.4-22.53-1.81-43.59-6.31-63.71-13.62zM320 352c-44.19 0-80-42.99-80-96 0-53.02 35.82-96 80-96s80 42.98 80 96c0 53.03-35.83 96-80 96zm272 27.78c-17.52-4.39-35.71-6.85-54.32-8.44 5.87-26.08 27.5-45.88 54.32-49.28v57.72zm0-236.11c-30.89-3.91-54.86-29.7-55.81-61.55 19.54 2.17 38.09 6.23 55.81 12.66v48.89z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d4edb5a elementor-widget elementor-widget-text-editor\" data-id=\"3d4edb5a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Ingresos<\/span> <span style=\"font-weight: 400;\">mensuales demostrables de al menos S\/ 1200.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3875f3ce\" data-id=\"3875f3ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a37a511 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a37a511\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-470874f elementor-widget elementor-widget-text-editor\" data-id=\"470874f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">M\u00ednimo 4 meses trabajando en cualquier empresa, incluyendo apps o tu negocio propio.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c28b36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c28b36\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-567dccf5\" data-id=\"567dccf5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29c1d1ee elementor-widget elementor-widget-image\" data-id=\"29c1d1ee\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.galgo.com\/pe\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"160\" height=\"39\" src=\"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/02\/logov3header.png\" class=\"attachment-large size-large wp-image-7701\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-294509cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"294509cc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c6a056b\" data-id=\"4c6a056b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfNecesitas financiar tu moto? \u00bfNecesitas financiar tu moto? Postula en el formulario y avanza con nuestros aliados de Galgo. Est\u00e1s a un par de clics de la moto de tus sue\u00f1os \u00bfCu\u00e1les son los requisitos para obtener un cr\u00e9dito de moto? Contar con DNI, CPP o CE Ingresos mensuales demostrables de al menos S\/ 1200. &#8230; <a title=\"Socopur\" class=\"read-more\" href=\"https:\/\/www.galgo.com\/pe\/socopur\" aria-label=\"More on Socopur\">Read more<\/a><\/p>\n","protected":false},"author":22,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Socopur - Galgo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.galgo.com\/pe\/socopur\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Socopur - Galgo\" \/>\n<meta property=\"og:description\" content=\"\u00bfNecesitas financiar tu moto? \u00bfNecesitas financiar tu moto? Postula en el formulario y avanza con nuestros aliados de Galgo. Est\u00e1s a un par de clics de la moto de tus sue\u00f1os \u00bfCu\u00e1les son los requisitos para obtener un cr\u00e9dito de moto? Contar con DNI, CPP o CE Ingresos mensuales demostrables de al menos S\/ 1200. ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.galgo.com\/pe\/socopur\" \/>\n<meta property=\"og:site_name\" content=\"Galgo\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-04T19:55:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/06\/galgologofooter-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.galgo.com\/pe\/socopur\",\"url\":\"https:\/\/www.galgo.com\/pe\/socopur\",\"name\":\"Socopur - Galgo\",\"isPartOf\":{\"@id\":\"https:\/\/www.galgo.com\/pe#website\"},\"datePublished\":\"2023-08-07T18:19:25+00:00\",\"dateModified\":\"2023-09-04T19:55:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.galgo.com\/pe\/socopur#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.galgo.com\/pe\/socopur\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.galgo.com\/pe\/socopur#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.galgo.com\/pe\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Socopur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.galgo.com\/pe#website\",\"url\":\"https:\/\/www.galgo.com\/pe\",\"name\":\"Galgo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.galgo.com\/pe#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.galgo.com\/pe?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.galgo.com\/pe#organization\",\"name\":\"Galgo\",\"url\":\"https:\/\/www.galgo.com\/pe\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.galgo.com\/pe#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/05\/logogalgo2.svg\",\"contentUrl\":\"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/05\/logogalgo2.svg\",\"width\":365,\"height\":117,\"caption\":\"Galgo\"},\"image\":{\"@id\":\"https:\/\/www.galgo.com\/pe#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Socopur - Galgo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.galgo.com\/pe\/socopur","og_locale":"es_ES","og_type":"article","og_title":"Socopur - Galgo","og_description":"\u00bfNecesitas financiar tu moto? \u00bfNecesitas financiar tu moto? Postula en el formulario y avanza con nuestros aliados de Galgo. Est\u00e1s a un par de clics de la moto de tus sue\u00f1os \u00bfCu\u00e1les son los requisitos para obtener un cr\u00e9dito de moto? Contar con DNI, CPP o CE Ingresos mensuales demostrables de al menos S\/ 1200. ... Read more","og_url":"https:\/\/www.galgo.com\/pe\/socopur","og_site_name":"Galgo","article_modified_time":"2023-09-04T19:55:00+00:00","og_image":[{"url":"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/06\/galgologofooter-1.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.galgo.com\/pe\/socopur","url":"https:\/\/www.galgo.com\/pe\/socopur","name":"Socopur - Galgo","isPartOf":{"@id":"https:\/\/www.galgo.com\/pe#website"},"datePublished":"2023-08-07T18:19:25+00:00","dateModified":"2023-09-04T19:55:00+00:00","breadcrumb":{"@id":"https:\/\/www.galgo.com\/pe\/socopur#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.galgo.com\/pe\/socopur"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.galgo.com\/pe\/socopur#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.galgo.com\/pe"},{"@type":"ListItem","position":2,"name":"Socopur"}]},{"@type":"WebSite","@id":"https:\/\/www.galgo.com\/pe#website","url":"https:\/\/www.galgo.com\/pe","name":"Galgo","description":"","publisher":{"@id":"https:\/\/www.galgo.com\/pe#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.galgo.com\/pe?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.galgo.com\/pe#organization","name":"Galgo","url":"https:\/\/www.galgo.com\/pe","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.galgo.com\/pe#\/schema\/logo\/image\/","url":"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/05\/logogalgo2.svg","contentUrl":"https:\/\/www.galgo.com\/wp-content\/uploads\/2023\/05\/logogalgo2.svg","width":365,"height":117,"caption":"Galgo"},"image":{"@id":"https:\/\/www.galgo.com\/pe#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.galgo.com\/pe\/wp-json\/wp\/v2\/pages\/27369"}],"collection":[{"href":"https:\/\/www.galgo.com\/pe\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.galgo.com\/pe\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.galgo.com\/pe\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.galgo.com\/pe\/wp-json\/wp\/v2\/comments?post=27369"}],"version-history":[{"count":49,"href":"https:\/\/www.galgo.com\/pe\/wp-json\/wp\/v2\/pages\/27369\/revisions"}],"predecessor-version":[{"id":28899,"href":"https:\/\/www.galgo.com\/pe\/wp-json\/wp\/v2\/pages\/27369\/revisions\/28899"}],"wp:attachment":[{"href":"https:\/\/www.galgo.com\/pe\/wp-json\/wp\/v2\/media?parent=27369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}